{"id":43228,"date":"2018-03-13T17:17:26","date_gmt":"2018-03-13T11:47:26","guid":{"rendered":"https:\/\/dusbus.com\/?p=43228"},"modified":"2018-03-13T17:17:26","modified_gmt":"2018-03-13T11:47:26","slug":"%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89","status":"publish","type":"post","link":"https:\/\/dusbus.com\/hi\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\/","title":{"rendered":"\u0907\u0902\u0921\u094b \u0935\u0947\u0938\u094d\u091f\u0930\u094d\u0928 \u0921\u094d\u0930\u0947\u0938\u0947\u0938 \u095e\u0949\u0930 \u0935\u0940\u092e\u0947\u0928 &#8211; \u0909\u0924\u094d\u0938\u0935 \u092b\u0948\u0936\u0928"},"content":{"rendered":"<h3><strong>\u0967.\u090f\u092e\u094d\u092c\u094d\u0930\u093e\u092f\u0921\u0930\u0921 \u0928\u0947\u091f \u0917\u093e\u0909\u0928- <\/strong><\/h3>\n<p>\u092f\u0947 \u0917\u093e\u0909\u0928 \u0928\u0947\u091f \u092b\u0948\u092c\u094d\u0930\u093f\u0915 \u092e\u0947\u0902 \u0909\u092a\u0932\u092c\u094d\u0927 \u0939\u0948\u0964<\/p>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-43230\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-1.jpg\" alt=\"\u090f\u092e\u094d\u092c\u094d\u0930\u093e\u092f\u0921\u0930\u0921 \u0928\u0947\u091f \u0917\u093e\u0909\u0928\" width=\"1000\" height=\"1447\" srcset=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-1.jpg 1000w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-1-690x998.jpg 690w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-1-104x150.jpg 104w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-1-768x1111.jpg 768w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-1-708x1024.jpg 708w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-1-500x724.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/h3>\n<p>&nbsp;<\/p>\n<p>\u092e\u0942\u0932\u094d\u092f- \u0930\u0942\u092a\u090f 5596\/-<\/p>\n<p><a href=\"https:\/\/www.utsavfashion.in\/product\/embroidered-net-gown-in-coral-and-beige-tjw250\" target=\"_blank\" rel=\"noopener nofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4945\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2016\/12\/Buy-Here-basket.png\" alt=\"Buy Here Basket\" width=\"48\" height=\"48\" \/>\u00a0\u092f\u0939\u093e\u0901 \u0938\u0947 \u0916\u0930\u0940\u0926\u0947\u0902\u00a0<\/a><\/p>\n<h3><strong>\u0968.\u090f\u092e\u094d\u092c\u094d\u0930\u093e\u092f\u0921\u0930\u0921 \u091c\u093e\u0930\u091c\u091f \u092a\u094d\u0932\u0940\u091f\u0947\u0921 \u0938\u093e\u095c\u0940 \u0938\u094d\u091f\u093e\u0907\u0932 \u0917\u093e\u0909\u0928- <\/strong><\/h3>\n<p>\u092f\u0947 \u0917\u093e\u0909\u0928 \u091c\u093e\u0930\u091c\u091f \u092b\u0948\u092c\u094d\u0930\u093f\u0915 \u092e\u0947\u0902 \u0909\u092a\u0932\u092c\u094d\u0927 \u0939\u0948\u0964<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-43231\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-2-1.jpg\" alt=\"\u090f\u092e\u094d\u092c\u094d\u0930\u093e\u092f\u0921\u0930\u0921 \u091c\u093e\u0930\u091c\u091f \u092a\u094d\u0932\u0940\u091f\u0947\u0921 \u0938\u093e\u095c\u0940 \u0938\u094d\u091f\u093e\u0907\u0932 \u0917\u093e\u0909\u0928\" width=\"1000\" height=\"1447\" srcset=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-2-1.jpg 1000w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-2-1-690x998.jpg 690w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-2-1-104x150.jpg 104w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-2-1-768x1111.jpg 768w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-2-1-708x1024.jpg 708w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-2-1-500x724.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>\u092e\u0942\u0932\u094d\u092f- \u0930\u0942\u092a\u090f 5919\/-<\/p>\n<p><a href=\"https:\/\/www.utsavfashion.in\/product\/embroidered-georgette-pleated-saree-style-gown-in-red-tjw289\" target=\"_blank\" rel=\"noopener nofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4945\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2016\/12\/Buy-Here-basket.png\" alt=\"Buy Here Basket\" width=\"48\" height=\"48\" \/>\u00a0\u092f\u0939\u093e\u0901 \u0938\u0947 \u0916\u0930\u0940\u0926\u0947\u0902\u00a0<\/a><\/p>\n<h3><strong>\u0969.\u0939\u0948\u0923\u094d\u0921 \u090f\u092e\u094d\u092c\u094d\u0930\u093e\u092f\u0921\u0930\u0921 \u0928\u0947\u0915 \u0932\u093e\u0907\u0928 \u0906\u0930\u094d\u091f \u0938\u093f\u0932\u094d\u0915 \u0917\u093e\u0909\u0928-<\/strong><\/h3>\n<p>\u092f\u0947 \u0917\u093e\u0909\u0928 \u0906\u0930\u094d\u091f \u0938\u093f\u0932\u094d\u0915 \u092b\u0948\u092c\u094d\u0930\u093f\u0915 \u092e\u0947\u0902 \u0909\u092a\u0932\u092c\u094d\u0927 \u0939\u0948\u0964<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-43233\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-3.jpg\" alt=\"\u0939\u0948\u0923\u094d\u0921 \u090f\u092e\u094d\u092c\u094d\u0930\u093e\u092f\u0921\u0930\u0921 \u0928\u0947\u0915 \u0932\u093e\u0907\u0928 \u0906\u0930\u094d\u091f \u0938\u093f\u0932\u094d\u0915 \u0917\u093e\u0909\u0928\" width=\"1000\" height=\"1447\" srcset=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-3.jpg 1000w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-3-690x998.jpg 690w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-3-104x150.jpg 104w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-3-768x1111.jpg 768w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-3-708x1024.jpg 708w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-3-500x724.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>\u092e\u0942\u0932\u094d\u092f- \u0930\u0942\u092a\u090f 3208\/-<\/p>\n<p><a href=\"https:\/\/www.utsavfashion.in\/product\/hand-embroidered-neckline-art-silk-gown-in-brown-ttv15\" target=\"_blank\" rel=\"noopener nofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4945\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2016\/12\/Buy-Here-basket.png\" alt=\"Buy Here Basket\" width=\"48\" height=\"48\" \/>\u00a0\u092f\u0939\u093e\u0901 \u0938\u0947 \u0916\u0930\u0940\u0926\u0947\u0902\u00a0<\/a><\/p>\n<h3><strong>\u096a.\u090f\u092e\u094d\u092c\u094d\u0930\u093e\u092f\u0921\u0930\u0921 \u0906\u0930\u094d\u091f \u0938\u093f\u0932\u094d\u0915 \u0917\u093e\u0909\u0928 \u0907\u0928 \u092a\u093f\u0902\u0915- <\/strong><\/h3>\n<p>\u092f\u0947 \u0917\u093e\u0909\u0928 \u0906\u0930\u094d\u091f \u0938\u093f\u0932\u094d\u0915 \u092b\u0948\u092c\u094d\u0930\u093f\u0915 \u092e\u0947\u0902 \u0909\u092a\u0932\u092c\u094d\u0927 \u0939\u0948\u0964<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-43234\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-4.jpg\" alt=\"\u090f\u092e\u094d\u092c\u094d\u0930\u093e\u092f\u0921\u0930\u0921 \u0906\u0930\u094d\u091f \u0938\u093f\u0932\u094d\u0915 \u0917\u093e\u0909\u0928 \u0907\u0928 \u092a\u093f\u0902\u0915\" width=\"1000\" height=\"1447\" srcset=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-4.jpg 1000w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-4-690x998.jpg 690w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-4-104x150.jpg 104w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-4-768x1111.jpg 768w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-4-708x1024.jpg 708w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-4-500x724.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>\u092e\u0942\u0932\u094d\u092f- \u0930\u0942\u092a\u090f 3272\/-<\/p>\n<p><a href=\"https:\/\/www.utsavfashion.in\/product\/embroidered-art-silk-gown-in-pink-tgw193\" target=\"_blank\" rel=\"noopener nofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4945\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2016\/12\/Buy-Here-basket.png\" alt=\"Buy Here Basket\" width=\"48\" height=\"48\" \/>\u00a0\u092f\u0939\u093e\u0901 \u0938\u0947 \u0916\u0930\u0940\u0926\u0947\u0902\u00a0<\/a><\/p>\n<h3><strong>\u096b.\u090f\u092e\u094d\u092c\u094d\u0930\u094b\u0907\u0921\u0930\u0921 \u0915\u094d\u0930\u0947\u092a \u0917\u093e\u0909\u0928- <\/strong><\/h3>\n<p>\u092f\u0947 \u0917\u093e\u0909\u0928 \u0906\u0930\u094d\u091f \u0938\u093f\u0932\u094d\u0915 crepe \u092b\u0948\u092c\u094d\u0930\u093f\u0915 \u092e\u0947\u0902 \u0909\u092a\u0932\u092c\u094d\u0927 \u0939\u0948\u0964<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-43235\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-5.jpg\" alt=\"\u092e\u094d\u092c\u094d\u0930\u094b\u0907\u0921\u0930\u0921 \u0915\u094d\u0930\u0947\u092a \u0917\u093e\u0909\u0928\" width=\"1000\" height=\"1447\" srcset=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-5.jpg 1000w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-5-690x998.jpg 690w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-5-104x150.jpg 104w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-5-768x1111.jpg 768w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-5-708x1024.jpg 708w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-5-500x724.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>\u092e\u0942\u0932\u094d\u092f- \u0930\u0942\u092a\u090f 3272\/-<\/p>\n<p><a href=\"https:\/\/www.utsavfashion.in\/product\/embroidered-crepe-gown-in-beige-and-blue-tgw199\" target=\"_blank\" rel=\"noopener nofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4945\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2016\/12\/Buy-Here-basket.png\" alt=\"Buy Here Basket\" width=\"48\" height=\"48\" \/>\u00a0\u092f\u0939\u093e\u0901 \u0938\u0947 \u0916\u0930\u0940\u0926\u0947\u0902\u00a0<\/a><\/p>\n<h3><strong>\u096c.\u090f\u092e\u094d\u092c\u094d\u0930\u093e\u092f\u0921\u0930\u0921 \u0906\u0930\u094d\u091f \u0938\u093f\u0932\u094d\u0915 \u091c\u0948\u0915\u0947\u091f \u0938\u094d\u091f\u093e\u0907\u0932 \u0917\u093e\u0909\u0928- <\/strong><\/h3>\n<p>\u092f\u0947 \u0917\u093e\u0909\u0928 \u0906\u0930\u094d\u091f \u0938\u093f\u0932\u094d\u0915 \u092b\u0948\u092c\u094d\u0930\u093f\u0915 \u092e\u0947\u0902 \u0909\u092a\u0932\u092c\u094d\u0927 \u0939\u0948\u0964<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-43236\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-6.jpg\" alt=\"\u090f\u092e\u094d\u092c\u094d\u0930\u093e\u092f\u0921\u0930\u0921 \u0906\u0930\u094d\u091f \u0938\u093f\u0932\u094d\u0915 \u091c\u0948\u0915\u0947\u091f \u0938\u094d\u091f\u093e\u0907\u0932 \u0917\u093e\u0909\u0928\" width=\"1000\" height=\"1447\" srcset=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-6.jpg 1000w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-6-690x998.jpg 690w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-6-104x150.jpg 104w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-6-768x1111.jpg 768w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-6-708x1024.jpg 708w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-6-500x724.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>\u092e\u0942\u0932\u094d\u092f- \u0930\u0942\u092a\u090f 5,672\/-<\/p>\n<p><a href=\"https:\/\/www.utsavfashion.in\/product\/embroidered-art-silk-jacket-style-gown-in-peach-and-blue-tgw29\" target=\"_blank\" rel=\"noopener nofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4945\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2016\/12\/Buy-Here-basket.png\" alt=\"Buy Here Basket\" width=\"48\" height=\"48\" \/>\u00a0\u092f\u0939\u093e\u0901 \u0938\u0947 \u0916\u0930\u0940\u0926\u0947\u0902\u00a0<\/a><\/p>\n<h3><strong>\u096d.\u0921\u093f\u091c\u093f\u091f\u0932 \u092a\u094d\u0930\u093f\u0902\u091f\u0947\u0921 \u0906\u0930\u094d\u091f \u0938\u093f\u0932\u094d\u0915 \u0917\u093e\u0909\u0928-<\/strong><\/h3>\n<p>\u092f\u0947 \u0917\u093e\u0909\u0928 \u0906\u0930\u094d\u091f \u0938\u093f\u0932\u094d\u0915 \u092b\u0948\u092c\u094d\u0930\u093f\u0915 \u092e\u0947\u0902 \u0909\u092a\u0932\u092c\u094d\u0927 \u0939\u0948\u0964<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-43237\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-7.jpg\" alt=\"\u0921\u093f\u091c\u093f\u091f\u0932 \u092a\u094d\u0930\u093f\u0902\u091f\u0947\u0921 \u0906\u0930\u094d\u091f \u0938\u093f\u0932\u094d\u0915 \u0917\u093e\u0909\u0928\" width=\"1000\" height=\"1447\" srcset=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-7.jpg 1000w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-7-690x998.jpg 690w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-7-104x150.jpg 104w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-7-768x1111.jpg 768w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-7-708x1024.jpg 708w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-7-500x724.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>\u092e\u0942\u0932\u094d\u092f- \u0930\u0942\u092a\u090f 3990\/-<\/p>\n<p><a href=\"https:\/\/www.utsavfashion.in\/product\/digital-printed-art-silk-gown-in-off-white-and-navy-blue-tgw229\" target=\"_blank\" rel=\"noopener nofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4945\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2016\/12\/Buy-Here-basket.png\" alt=\"Buy Here Basket\" width=\"48\" height=\"48\" \/>\u00a0\u092f\u0939\u093e\u0901 \u0938\u0947 \u0916\u0930\u0940\u0926\u0947\u0902\u00a0<\/a><\/p>\n<h3><strong>\u096e.\u090f\u092e\u094d\u092c\u094d\u0930\u093e\u092f\u0921\u0930\u0921 \u0928\u0947\u091f \u090f\u0902\u0921 \u0906\u0930\u094d\u091f \u0938\u093f\u0932\u094d\u0915 \u0917\u093e\u0909\u0928-<\/strong><\/h3>\n<p>\u092f\u0947 \u0917\u093e\u0909\u0928 \u0906\u0930\u094d\u091f \u0938\u093f\u0932\u094d\u0915 \u0914\u0930 \u0928\u0947\u091f \u092b\u0948\u092c\u094d\u0930\u093f\u0915 \u092e\u0947\u0902 \u0909\u092a\u0932\u092c\u094d\u0927 \u0939\u0948\u0964<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-43238\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-8.jpg\" alt=\"\u090f\u092e\u094d\u092c\u094d\u0930\u093e\u092f\u0921\u0930\u0921 \u0928\u0947\u091f \u090f\u0902\u0921 \u0906\u0930\u094d\u091f \u0938\u093f\u0932\u094d\u0915 \u0917\u093e\u0909\u0928\" width=\"1000\" height=\"1447\" srcset=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-8.jpg 1000w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-8-690x998.jpg 690w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-8-104x150.jpg 104w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-8-768x1111.jpg 768w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-8-708x1024.jpg 708w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-8-500x724.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>\u092e\u0942\u0932\u094d\u092f- \u0930\u0942\u092a\u090f 8870\/-<\/p>\n<p><a href=\"https:\/\/www.utsavfashion.in\/product\/embroidered-net-and-art-silk-gown-in-orange-tgv2\" target=\"_blank\" rel=\"noopener nofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4945\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2016\/12\/Buy-Here-basket.png\" alt=\"Buy Here Basket\" width=\"48\" height=\"48\" \/>\u00a0\u092f\u0939\u093e\u0901 \u0938\u0947 \u0916\u0930\u0940\u0926\u0947\u0902\u00a0<\/a><\/p>\n<h3><strong>\u096f.\u0938\u093f\u0915\u094d\u0935\u093f\u0928\u0938 \u090f\u092e\u094d\u092c\u094d\u0930\u0949\u0907\u0921\u0947\u0930\u0921 \u0921\u094d\u0930\u0947\u092a\u093f\u0902\u0917 \u0921\u094d\u0930\u0947\u0938- <\/strong><\/h3>\n<p>\u092f\u0947 \u0921\u094d\u0930\u0947\u0938 \u0917\u094b\u0932\u094d\u0921\u0928 \u0914\u0930 \u0930\u0947\u0921 \u0915\u0932\u0930 \u092e\u0947\u0902 \u0909\u092a\u0932\u092c\u094d\u0927 \u0939\u0948\u0964<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-43239\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-9.jpg\" alt=\"\u0938\u093f\u0915\u094d\u0935\u093f\u0928\u0938 \u090f\u092e\u094d\u092c\u094d\u0930\u0949\u0907\u0921\u0947\u0930\u0921 \u0921\u094d\u0930\u0947\u092a\u093f\u0902\u0917 \u0921\u094d\u0930\u0947\u0938\" width=\"1000\" height=\"1447\" srcset=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-9.jpg 1000w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-9-690x998.jpg 690w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-9-104x150.jpg 104w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-9-768x1111.jpg 768w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-9-708x1024.jpg 708w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-9-500x724.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>\u092e\u0942\u0932\u094d\u092f-\u0930\u0941\u092a\u092f\u0947 3900\/-<\/p>\n<p><a href=\"https:\/\/www.utsavfashion.in\/product\/sequins-embroidered-lycra-draping-dress-in-red-and-golden-thu888\" target=\"_blank\" rel=\"noopener nofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4945\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2016\/12\/Buy-Here-basket.png\" alt=\"Buy Here Basket\" width=\"48\" height=\"48\" \/>\u00a0\u092f\u0939\u093e\u0901 \u0938\u0947 \u0916\u0930\u0940\u0926\u0947\u0902\u00a0<\/a><\/p>\n<h3><strong>\u0967\u0966.\u090f\u092e\u094d\u092c\u094d\u0930\u0949\u0907\u0921\u0947\u0930\u0921 \u091c\u0949\u0930\u091c\u0947\u091f \u091f\u0949\u092a \u0935\u093f\u0925 \u0927\u094b\u0924\u0940 \u092a\u0948\u0902\u091f-<\/strong><\/h3>\n<p>\u0907\u0938 \u0921\u094d\u0930\u0947\u0938 \u092a\u0930 \u0917\u094b\u0932\u094d\u0921\u0928 \u095b\u0930\u0940 \u0915\u0940 \u0917\u0908 \u0939\u0948 \u0914\u0930 \u092f\u0947 \u092c\u094d\u0932\u0942 \u0914\u0930 \u0930\u0947\u0921 \u0915\u0932\u0930 \u092e\u0947\u0902 \u0909\u092a\u0932\u092c\u094d\u0927 \u0939\u0948\u0964<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-43240\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-10.jpg\" alt=\"\u090f\u092e\u094d\u092c\u094d\u0930\u0949\u0907\u0921\u0947\u0930\u0921 \u091c\u0949\u0930\u091c\u0947\u091f \u091f\u0949\u092a \u0935\u093f\u0925 \u0927\u094b\u0924\u0940 \u092a\u0948\u0902\u091f\" width=\"1000\" height=\"1447\" srcset=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-10.jpg 1000w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-10-690x998.jpg 690w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-10-104x150.jpg 104w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-10-768x1111.jpg 768w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-10-708x1024.jpg 708w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-10-500x724.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><br \/>\n\u092e\u0942\u0932\u094d\u092f-\u0930\u0941\u092a\u092f\u0947 5,944\/-<\/p>\n<p><a href=\"https:\/\/www.utsavfashion.in\/product\/embroidered-georgette-top-with-dhoti-pant-in-red-tuz6?nosto=nosto-page-category2\" target=\"_blank\" rel=\"noopener nofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4945\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2016\/12\/Buy-Here-basket.png\" alt=\"Buy Here Basket\" width=\"48\" height=\"48\" \/>\u00a0\u092f\u0939\u093e\u0901 \u0938\u0947 \u0916\u0930\u0940\u0926\u0947\u0902\u00a0<\/a><\/p>\n<h3><strong>\u0967\u0967.\u092a\u094d\u0932\u0947\u0928 \u091c\u0949\u0930\u091c\u0947\u091f \u0927\u094b\u0924\u0940 \u0938\u094d\u091f\u093e\u0907\u0932 \u091f\u094d\u092f\u0942\u0928\u093f\u0915- <\/strong><\/h3>\n<p>\u092f\u0947 \u0921\u094d\u0930\u0947\u0938 \u092a\u0940\u091a \u0915\u0932\u0930 \u092e\u0947\u0902 \u0909\u092a\u0932\u092c\u094d\u0927 \u0939\u0948\u0964<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-43241\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-11.jpg\" alt=\"\u092a\u094d\u0932\u0947\u0928 \u091c\u0949\u0930\u091c\u0947\u091f \u0927\u094b\u0924\u0940 \u0938\u094d\u091f\u093e\u0907\u0932 \u091f\u094d\u092f\u0942\u0928\u093f\u0915\" width=\"1000\" height=\"1447\" srcset=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-11.jpg 1000w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-11-690x998.jpg 690w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-11-104x150.jpg 104w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-11-768x1111.jpg 768w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-11-708x1024.jpg 708w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-11-500x724.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>\u092e\u0942\u0932\u094d\u092f-\u0930\u0941\u092a\u092f\u0947 3,464\/-<\/p>\n<p><a href=\"https:\/\/www.utsavfashion.in\/product\/plain-georgette-dhoti-style-tunic-in-peach-thu236\" target=\"_blank\" rel=\"noopener nofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4945\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2016\/12\/Buy-Here-basket.png\" alt=\"Buy Here Basket\" width=\"48\" height=\"48\" \/>\u00a0\u092f\u0939\u093e\u0901 \u0938\u0947 \u0916\u0930\u0940\u0926\u0947\u0902\u00a0<\/a><\/p>\n<h3><strong>\u0967<\/strong><strong>\u0968. \u0939\u0948\u0902\u0921 \u090f\u092e\u094d\u092c\u094d\u0930\u0949\u0907\u0921\u0947\u0930\u0921 \u091c\u0949\u0930\u091c\u0947\u091f \u091f\u0949\u092a \u090f\u0902\u0921 \u0927\u094b\u0924\u0940 \u092a\u0948\u0902\u091f- <\/strong><\/h3>\n<p>\u0935\u0928 \u0936\u094b\u0932\u094d\u0921\u0930 \u091f\u0949\u092a \u0914\u0930 \u0927\u094b\u0924\u0940 \u092a\u0948\u0902\u091f \u0911\u092b \u0935\u093e\u0907\u091f \u0915\u0932\u0930 \u092e\u0947\u0902 \u0909\u092a\u0932\u092c\u094d\u0927 \u0939\u0948\u0964<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-43242\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-12.jpg\" alt=\"\u0939\u0948\u0902\u0921 \u090f\u092e\u094d\u092c\u094d\u0930\u0949\u0907\u0921\u0947\u0930\u0921 \u091c\u0949\u0930\u091c\u0947\u091f \u091f\u0949\u092a \u090f\u0902\u0921 \u0927\u094b\u0924\u0940 \u092a\u0948\u0902\u091f\" width=\"1000\" height=\"1447\" srcset=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-12.jpg 1000w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-12-690x998.jpg 690w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-12-104x150.jpg 104w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-12-768x1111.jpg 768w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-12-708x1024.jpg 708w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-12-500x724.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>\u092e\u0942\u0932\u094d\u092f-\u0930\u0941\u092a\u092f\u0947 5,473\/-<\/p>\n<p><a href=\"https:\/\/www.utsavfashion.in\/product\/hand-embroidered-georgette-top-n-dhoti-pant-in-peach-tzg33\" target=\"_blank\" rel=\"noopener nofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4945\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2016\/12\/Buy-Here-basket.png\" alt=\"Buy Here Basket\" width=\"48\" height=\"48\" \/>\u00a0\u092f\u0939\u093e\u0901 \u0938\u0947 \u0916\u0930\u0940\u0926\u0947\u0902\u00a0<\/a><\/p>\n<h3><strong>\u0967\u0969. \u0939\u0948\u0902\u0921 \u090f\u092e\u094d\u092c\u094d\u0930\u093e\u0907\u0921\u0930\u0921 \u091c\u0949\u0930\u091c\u0947\u091f \u0917\u093e\u0909\u0928-<\/strong><\/h3>\n<p>\u092f\u0947 \u0917\u093e\u0909\u0928 \u0921\u093e\u0930\u094d\u0915 \u091f\u0940\u0932 \u092c\u094d\u0932\u0942 \u0915\u0932\u0930 \u092e\u0947\u0902 \u0909\u092a\u0932\u092c\u094d\u0927 \u0939\u0948\u0964<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-43243\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-1-1.jpg\" alt=\"\u0939\u0948\u0902\u0921 \u090f\u092e\u094d\u092c\u094d\u0930\u093e\u0907\u0921\u0930\u0921 \u091c\u0949\u0930\u091c\u0947\u091f \u0917\u093e\u0909\u0928\" width=\"1000\" height=\"1447\" srcset=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-1-1.jpg 1000w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-1-1-690x998.jpg 690w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-1-1-104x150.jpg 104w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-1-1-768x1111.jpg 768w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-1-1-708x1024.jpg 708w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-1-1-500x724.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>\u092e\u0942\u0932\u094d\u092f-\u0930\u0941\u092a\u092f\u0947 13,518\/-<\/p>\n<p><a href=\"https:\/\/www.utsavfashion.in\/product\/hand-embroidered-georgette-gown-in-dark-teal-blue-tsp159\" target=\"_blank\" rel=\"noopener nofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4945\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2016\/12\/Buy-Here-basket.png\" alt=\"Buy Here Basket\" width=\"48\" height=\"48\" \/>\u00a0\u092f\u0939\u093e\u0901 \u0938\u0947 \u0916\u0930\u0940\u0926\u0947\u0902\u00a0<\/a><\/p>\n<h3><strong>\u0967\u096a. \u092a\u094d\u0932\u0947\u0928 \u091c\u0949\u0930\u091c\u0947\u091f \u0927\u094b\u0924\u0940 \u0938\u094d\u091f\u093e\u0907\u0932 \u091f\u094d\u092f\u0942\u0928\u093f\u0915- <\/strong><\/h3>\n<p>\u092f\u0947 \u0921\u094d\u0930\u0947\u0938 \u0911\u0930\u0947\u0902\u091c \u0915\u0932\u0930 \u092e\u0947\u0902 \u0909\u092a\u0932\u092c\u094d\u0927 \u0939\u0948\u0964<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-43245\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-2-2.jpg\" alt=\"\u092a\u094d\u0932\u0947\u0928 \u091c\u0949\u0930\u091c\u0947\u091f \u0927\u094b\u0924\u0940 \u0938\u094d\u091f\u093e\u0907\u0932 \u091f\u094d\u092f\u0942\u0928\u093f\u0915\" width=\"1000\" height=\"1447\" srcset=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-2-2.jpg 1000w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-2-2-690x998.jpg 690w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-2-2-104x150.jpg 104w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-2-2-768x1111.jpg 768w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-2-2-708x1024.jpg 708w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-2-2-500x724.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>\u092e\u0942\u0932\u094d\u092f-\u0930\u0941\u092a\u092f\u0947 2615\/-<\/p>\n<p><a href=\"https:\/\/www.utsavfashion.in\/product\/plain-georgette-dhoti-style-tunic-in-orange-tuz21\" target=\"_blank\" rel=\"noopener nofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4945\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2016\/12\/Buy-Here-basket.png\" alt=\"Buy Here Basket\" width=\"48\" height=\"48\" \/>\u00a0\u092f\u0939\u093e\u0901 \u0938\u0947 \u0916\u0930\u0940\u0926\u0947\u0902\u00a0<\/a><\/p>\n<h3>\u0967\u096b.\u0939\u0948\u0902\u0921 \u090f\u092e\u094d\u092c\u094d\u0930\u0949\u0907\u0921\u0947\u0930\u0921 \u091c\u0949\u0930\u091c\u0947\u091f \u0932\u0947\u092f\u0930\u094d\u0921 \u0917\u093e\u0909\u0928-<\/h3>\n<p>\u092f\u0947 \u0917\u093e\u0909\u0928 \u092a\u0947\u0938\u094d\u091f\u0932 \u0917\u094d\u0930\u0940\u0928 \u0914\u0930 \u092a\u0947\u0938\u094d\u091f\u0932 \u0911\u0930\u0947\u0902\u091c \u0915\u0932\u0930 \u092e\u0947\u0902 \u0909\u092a\u0932\u092c\u094d\u0927 \u0939\u0948\u0964<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-43246\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-3-1.jpg\" alt=\"\u0939\u0948\u0902\u0921 \u090f\u092e\u094d\u092c\u094d\u0930\u0949\u0907\u0921\u0947\u0930\u0921 \u091c\u0949\u0930\u091c\u0947\u091f \u0932\u0947\u092f\u0930\u094d\u0921 \u0917\u093e\u0909\u0928\" width=\"1000\" height=\"1447\" srcset=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-3-1.jpg 1000w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-3-1-690x998.jpg 690w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-3-1-104x150.jpg 104w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-3-1-768x1111.jpg 768w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-3-1-708x1024.jpg 708w, https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress-3-1-500x724.jpg 500w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>\u092e\u0942\u0932\u094d\u092f-\u0930\u0941\u092a\u092f\u0947 4,864\/-<\/p>\n<p><a href=\"https:\/\/www.utsavfashion.in\/product\/hand-embroidered-georgette-layered-gown-in-orange-and-green-tjw619\" target=\"_blank\" rel=\"noopener nofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4945\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2016\/12\/Buy-Here-basket.png\" alt=\"Buy Here Basket\" width=\"48\" height=\"48\" \/>\u00a0\u092f\u0939\u093e\u0901 \u0938\u0947 \u0916\u0930\u0940\u0926\u0947\u0902\u00a0<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0967.\u090f\u092e\u094d\u092c\u094d\u0930\u093e\u092f\u0921\u0930\u0921 \u0928\u0947\u091f \u0917\u093e\u0909\u0928- \u092f\u0947 \u0917\u093e\u0909\u0928 \u0928\u0947\u091f \u092b\u0948\u092c\u094d\u0930\u093f\u0915 \u092e\u0947\u0902 \u0909\u092a\u0932\u092c\u094d\u0927 \u0939\u0948\u0964 &nbsp; \u092e\u0942\u0932\u094d\u092f- \u0930\u0942\u092a\u090f 5596\/- \u00a0\u092f\u0939\u093e\u0901 \u0938\u0947 \u0916\u0930\u0940\u0926\u0947\u0902\u00a0 \u0968.\u090f\u092e\u094d\u092c\u094d\u0930\u093e\u092f\u0921\u0930\u0921 \u091c\u093e\u0930\u091c\u091f \u092a\u094d\u0932\u0940\u091f\u0947\u0921 \u0938\u093e\u095c\u0940 \u0938\u094d\u091f\u093e\u0907\u0932 \u0917\u093e\u0909\u0928- \u092f\u0947 \u0917\u093e\u0909\u0928 \u091c\u093e\u0930\u091c\u091f \u092b\u0948\u092c\u094d\u0930\u093f\u0915 \u092e\u0947\u0902 \u0909\u092a\u0932\u092c\u094d\u0927 \u0939\u0948\u0964 \u092e\u0942\u0932\u094d\u092f- \u0930\u0942\u092a\u090f 5919\/- \u00a0\u092f\u0939\u093e\u0901 \u0938\u0947 \u0916\u0930\u0940\u0926\u0947\u0902\u00a0 \u0969.\u0939\u0948\u0923\u094d\u0921 \u090f\u092e\u094d\u092c\u094d\u0930\u093e\u092f\u0921\u0930\u0921 \u0928\u0947\u0915 \u0932\u093e\u0907\u0928 \u0906\u0930\u094d\u091f \u0938\u093f\u0932\u094d\u0915 \u0917\u093e\u0909\u0928- \u092f\u0947 \u0917\u093e\u0909\u0928 \u0906\u0930\u094d\u091f \u0938\u093f\u0932\u094d\u0915 \u092b\u0948\u092c\u094d\u0930\u093f\u0915 \u092e\u0947\u0902 \u0909\u092a\u0932\u092c\u094d\u0927 \u0939\u0948\u0964 \u092e\u0942\u0932\u094d\u092f- \u0930\u0942\u092a\u090f 3208\/- \u00a0\u092f\u0939\u093e\u0901 [&hellip;]<\/p>\n","protected":false},"author":73,"featured_media":43249,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[81,44],"tags":[],"class_list":{"0":"post-43228","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-fashion-lifestyle-hi","8":"category-most-popular-hi","9":"entry"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0907\u0902\u0921\u094b \u0935\u0947\u0938\u094d\u091f\u0930\u094d\u0928 \u0921\u094d\u0930\u0947\u0938\u0947\u0938 \u095e\u0949\u0930 \u0935\u0940\u092e\u0947\u0928 - \u0909\u0924\u094d\u0938\u0935 \u092b\u0948\u0936\u0928 - DusBus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dusbus.com\/hi\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\/\" \/>\n<meta property=\"og:locale\" content=\"hi_IN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0907\u0902\u0921\u094b \u0935\u0947\u0938\u094d\u091f\u0930\u094d\u0928 \u0921\u094d\u0930\u0947\u0938\u0947\u0938 \u095e\u0949\u0930 \u0935\u0940\u092e\u0947\u0928 - \u0909\u0924\u094d\u0938\u0935 \u092b\u0948\u0936\u0928 - DusBus\" \/>\n<meta property=\"og:description\" content=\"\u0967.\u090f\u092e\u094d\u092c\u094d\u0930\u093e\u092f\u0921\u0930\u0921 \u0928\u0947\u091f \u0917\u093e\u0909\u0928- \u092f\u0947 \u0917\u093e\u0909\u0928 \u0928\u0947\u091f \u092b\u0948\u092c\u094d\u0930\u093f\u0915 \u092e\u0947\u0902 \u0909\u092a\u0932\u092c\u094d\u0927 \u0939\u0948\u0964 &nbsp; \u092e\u0942\u0932\u094d\u092f- \u0930\u0942\u092a\u090f 5596\/- \u00a0\u092f\u0939\u093e\u0901 \u0938\u0947 \u0916\u0930\u0940\u0926\u0947\u0902\u00a0 \u0968.\u090f\u092e\u094d\u092c\u094d\u0930\u093e\u092f\u0921\u0930\u0921 \u091c\u093e\u0930\u091c\u091f \u092a\u094d\u0932\u0940\u091f\u0947\u0921 \u0938\u093e\u095c\u0940 \u0938\u094d\u091f\u093e\u0907\u0932 \u0917\u093e\u0909\u0928- \u092f\u0947 \u0917\u093e\u0909\u0928 \u091c\u093e\u0930\u091c\u091f \u092b\u0948\u092c\u094d\u0930\u093f\u0915 \u092e\u0947\u0902 \u0909\u092a\u0932\u092c\u094d\u0927 \u0939\u0948\u0964 \u092e\u0942\u0932\u094d\u092f- \u0930\u0942\u092a\u090f 5919\/- \u00a0\u092f\u0939\u093e\u0901 \u0938\u0947 \u0916\u0930\u0940\u0926\u0947\u0902\u00a0 \u0969.\u0939\u0948\u0923\u094d\u0921 \u090f\u092e\u094d\u092c\u094d\u0930\u093e\u092f\u0921\u0930\u0921 \u0928\u0947\u0915 \u0932\u093e\u0907\u0928 \u0906\u0930\u094d\u091f \u0938\u093f\u0932\u094d\u0915 \u0917\u093e\u0909\u0928- \u092f\u0947 \u0917\u093e\u0909\u0928 \u0906\u0930\u094d\u091f \u0938\u093f\u0932\u094d\u0915 \u092b\u0948\u092c\u094d\u0930\u093f\u0915 \u092e\u0947\u0902 \u0909\u092a\u0932\u092c\u094d\u0927 \u0939\u0948\u0964 \u092e\u0942\u0932\u094d\u092f- \u0930\u0942\u092a\u090f 3208\/- \u00a0\u092f\u0939\u093e\u0901 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dusbus.com\/hi\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\/\" \/>\n<meta property=\"og:site_name\" content=\"DusBus\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DusBusOfficial\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-13T11:47:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"222\" \/>\n\t<meta property=\"og:image:height\" content=\"281\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pooja Jaiswal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DusBusOfficial\" \/>\n<meta name=\"twitter:site\" content=\"@DusBusOfficial\" \/>\n<meta name=\"twitter:label1\" content=\"\u0926\u094d\u0935\u093e\u0930\u093e \u0932\u093f\u0916\u093f\u0924\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pooja Jaiswal\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\\\/\"},\"author\":{\"name\":\"Pooja Jaiswal\",\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/#\\\/schema\\\/person\\\/23b1b2482f8d18ed52a0e8d890d99529\"},\"headline\":\"\u0907\u0902\u0921\u094b \u0935\u0947\u0938\u094d\u091f\u0930\u094d\u0928 \u0921\u094d\u0930\u0947\u0938\u0947\u0938 \u095e\u0949\u0930 \u0935\u0940\u092e\u0947\u0928 &#8211; \u0909\u0924\u094d\u0938\u0935 \u092b\u0948\u0936\u0928\",\"datePublished\":\"2018-03-13T11:47:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\\\/\"},\"wordCount\":49,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dusbus.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Dress.jpg\",\"articleSection\":[\"Fashion &amp; Lifestyle\",\"Most-Popular\"],\"inLanguage\":\"hi-IN\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dusbus.com\\\/hi\\\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\\\/\",\"url\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\\\/\",\"name\":\"\u0907\u0902\u0921\u094b \u0935\u0947\u0938\u094d\u091f\u0930\u094d\u0928 \u0921\u094d\u0930\u0947\u0938\u0947\u0938 \u095e\u0949\u0930 \u0935\u0940\u092e\u0947\u0928 - \u0909\u0924\u094d\u0938\u0935 \u092b\u0948\u0936\u0928 - DusBus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dusbus.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Dress.jpg\",\"datePublished\":\"2018-03-13T11:47:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\\\/#breadcrumb\"},\"inLanguage\":\"hi-IN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dusbus.com\\\/hi\\\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hi-IN\",\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dusbus.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Dress.jpg\",\"contentUrl\":\"https:\\\/\\\/dusbus.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Dress.jpg\",\"width\":222,\"height\":281,\"caption\":\"\u0917\u093e\u0909\u0928\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0907\u0902\u0921\u094b \u0935\u0947\u0938\u094d\u091f\u0930\u094d\u0928 \u0921\u094d\u0930\u0947\u0938\u0947\u0938 \u095e\u0949\u0930 \u0935\u0940\u092e\u0947\u0928 &#8211; \u0909\u0924\u094d\u0938\u0935 \u092b\u0948\u0936\u0928\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/#website\",\"url\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/\",\"name\":\"DusBus\",\"description\":\"Driving E-Commerce\",\"publisher\":{\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hi-IN\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/#organization\",\"name\":\"The August Company\",\"url\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hi-IN\",\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dusbus.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/dusbus-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/dusbus.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/dusbus-logo.jpg\",\"width\":99,\"height\":60,\"caption\":\"The August Company\"},\"image\":{\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DusBusOfficial\\\/\",\"https:\\\/\\\/x.com\\\/DusBusOfficial\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC76y6Ny1UxTRrXGhcKW2vzA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/#\\\/schema\\\/person\\\/23b1b2482f8d18ed52a0e8d890d99529\",\"name\":\"Pooja Jaiswal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hi-IN\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fde0fd69e6bde1e0b5e17aab5d3a37d04d3b6ce9b1aae1a501402489cca55abe?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fde0fd69e6bde1e0b5e17aab5d3a37d04d3b6ce9b1aae1a501402489cca55abe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fde0fd69e6bde1e0b5e17aab5d3a37d04d3b6ce9b1aae1a501402489cca55abe?s=96&d=mm&r=g\",\"caption\":\"Pooja Jaiswal\"},\"sameAs\":[\"http:\\\/\\\/dusbus.com\\\/hi\"],\"url\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/author\\\/pooja\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0907\u0902\u0921\u094b \u0935\u0947\u0938\u094d\u091f\u0930\u094d\u0928 \u0921\u094d\u0930\u0947\u0938\u0947\u0938 \u095e\u0949\u0930 \u0935\u0940\u092e\u0947\u0928 - \u0909\u0924\u094d\u0938\u0935 \u092b\u0948\u0936\u0928 - DusBus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dusbus.com\/hi\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\/","og_locale":"hi_IN","og_type":"article","og_title":"\u0907\u0902\u0921\u094b \u0935\u0947\u0938\u094d\u091f\u0930\u094d\u0928 \u0921\u094d\u0930\u0947\u0938\u0947\u0938 \u095e\u0949\u0930 \u0935\u0940\u092e\u0947\u0928 - \u0909\u0924\u094d\u0938\u0935 \u092b\u0948\u0936\u0928 - DusBus","og_description":"\u0967.\u090f\u092e\u094d\u092c\u094d\u0930\u093e\u092f\u0921\u0930\u0921 \u0928\u0947\u091f \u0917\u093e\u0909\u0928- \u092f\u0947 \u0917\u093e\u0909\u0928 \u0928\u0947\u091f \u092b\u0948\u092c\u094d\u0930\u093f\u0915 \u092e\u0947\u0902 \u0909\u092a\u0932\u092c\u094d\u0927 \u0939\u0948\u0964 &nbsp; \u092e\u0942\u0932\u094d\u092f- \u0930\u0942\u092a\u090f 5596\/- \u00a0\u092f\u0939\u093e\u0901 \u0938\u0947 \u0916\u0930\u0940\u0926\u0947\u0902\u00a0 \u0968.\u090f\u092e\u094d\u092c\u094d\u0930\u093e\u092f\u0921\u0930\u0921 \u091c\u093e\u0930\u091c\u091f \u092a\u094d\u0932\u0940\u091f\u0947\u0921 \u0938\u093e\u095c\u0940 \u0938\u094d\u091f\u093e\u0907\u0932 \u0917\u093e\u0909\u0928- \u092f\u0947 \u0917\u093e\u0909\u0928 \u091c\u093e\u0930\u091c\u091f \u092b\u0948\u092c\u094d\u0930\u093f\u0915 \u092e\u0947\u0902 \u0909\u092a\u0932\u092c\u094d\u0927 \u0939\u0948\u0964 \u092e\u0942\u0932\u094d\u092f- \u0930\u0942\u092a\u090f 5919\/- \u00a0\u092f\u0939\u093e\u0901 \u0938\u0947 \u0916\u0930\u0940\u0926\u0947\u0902\u00a0 \u0969.\u0939\u0948\u0923\u094d\u0921 \u090f\u092e\u094d\u092c\u094d\u0930\u093e\u092f\u0921\u0930\u0921 \u0928\u0947\u0915 \u0932\u093e\u0907\u0928 \u0906\u0930\u094d\u091f \u0938\u093f\u0932\u094d\u0915 \u0917\u093e\u0909\u0928- \u092f\u0947 \u0917\u093e\u0909\u0928 \u0906\u0930\u094d\u091f \u0938\u093f\u0932\u094d\u0915 \u092b\u0948\u092c\u094d\u0930\u093f\u0915 \u092e\u0947\u0902 \u0909\u092a\u0932\u092c\u094d\u0927 \u0939\u0948\u0964 \u092e\u0942\u0932\u094d\u092f- \u0930\u0942\u092a\u090f 3208\/- \u00a0\u092f\u0939\u093e\u0901 [&hellip;]","og_url":"https:\/\/dusbus.com\/hi\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\/","og_site_name":"DusBus","article_publisher":"https:\/\/www.facebook.com\/DusBusOfficial\/","article_published_time":"2018-03-13T11:47:26+00:00","og_image":[{"width":222,"height":281,"url":"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress.jpg","type":"image\/jpeg"}],"author":"Pooja Jaiswal","twitter_card":"summary_large_image","twitter_creator":"@DusBusOfficial","twitter_site":"@DusBusOfficial","twitter_misc":{"\u0926\u094d\u0935\u093e\u0930\u093e \u0932\u093f\u0916\u093f\u0924":"Pooja Jaiswal"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dusbus.com\/hi\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\/#article","isPartOf":{"@id":"https:\/\/dusbus.com\/hi\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\/"},"author":{"name":"Pooja Jaiswal","@id":"https:\/\/dusbus.com\/hi\/#\/schema\/person\/23b1b2482f8d18ed52a0e8d890d99529"},"headline":"\u0907\u0902\u0921\u094b \u0935\u0947\u0938\u094d\u091f\u0930\u094d\u0928 \u0921\u094d\u0930\u0947\u0938\u0947\u0938 \u095e\u0949\u0930 \u0935\u0940\u092e\u0947\u0928 &#8211; \u0909\u0924\u094d\u0938\u0935 \u092b\u0948\u0936\u0928","datePublished":"2018-03-13T11:47:26+00:00","mainEntityOfPage":{"@id":"https:\/\/dusbus.com\/hi\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\/"},"wordCount":49,"commentCount":0,"publisher":{"@id":"https:\/\/dusbus.com\/hi\/#organization"},"image":{"@id":"https:\/\/dusbus.com\/hi\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\/#primaryimage"},"thumbnailUrl":"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress.jpg","articleSection":["Fashion &amp; Lifestyle","Most-Popular"],"inLanguage":"hi-IN","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dusbus.com\/hi\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dusbus.com\/hi\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\/","url":"https:\/\/dusbus.com\/hi\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\/","name":"\u0907\u0902\u0921\u094b \u0935\u0947\u0938\u094d\u091f\u0930\u094d\u0928 \u0921\u094d\u0930\u0947\u0938\u0947\u0938 \u095e\u0949\u0930 \u0935\u0940\u092e\u0947\u0928 - \u0909\u0924\u094d\u0938\u0935 \u092b\u0948\u0936\u0928 - DusBus","isPartOf":{"@id":"https:\/\/dusbus.com\/hi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dusbus.com\/hi\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\/#primaryimage"},"image":{"@id":"https:\/\/dusbus.com\/hi\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\/#primaryimage"},"thumbnailUrl":"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress.jpg","datePublished":"2018-03-13T11:47:26+00:00","breadcrumb":{"@id":"https:\/\/dusbus.com\/hi\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\/#breadcrumb"},"inLanguage":"hi-IN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dusbus.com\/hi\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\/"]}]},{"@type":"ImageObject","inLanguage":"hi-IN","@id":"https:\/\/dusbus.com\/hi\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\/#primaryimage","url":"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress.jpg","contentUrl":"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress.jpg","width":222,"height":281,"caption":"\u0917\u093e\u0909\u0928"},{"@type":"BreadcrumbList","@id":"https:\/\/dusbus.com\/hi\/%e0%a4%87%e0%a4%82%e0%a4%a1%e0%a5%8b-%e0%a4%b5%e0%a5%87%e0%a4%b8%e0%a5%8d%e0%a4%9f%e0%a4%b0%e0%a5%8d%e0%a4%a8-%e0%a4%a1%e0%a5%8d%e0%a4%b0%e0%a5%87%e0%a4%b8%e0%a5%87%e0%a4%b8-%e0%a5%9e%e0%a5%89\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dusbus.com\/hi\/"},{"@type":"ListItem","position":2,"name":"\u0907\u0902\u0921\u094b \u0935\u0947\u0938\u094d\u091f\u0930\u094d\u0928 \u0921\u094d\u0930\u0947\u0938\u0947\u0938 \u095e\u0949\u0930 \u0935\u0940\u092e\u0947\u0928 &#8211; \u0909\u0924\u094d\u0938\u0935 \u092b\u0948\u0936\u0928"}]},{"@type":"WebSite","@id":"https:\/\/dusbus.com\/hi\/#website","url":"https:\/\/dusbus.com\/hi\/","name":"DusBus","description":"Driving E-Commerce","publisher":{"@id":"https:\/\/dusbus.com\/hi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dusbus.com\/hi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hi-IN"},{"@type":"Organization","@id":"https:\/\/dusbus.com\/hi\/#organization","name":"The August Company","url":"https:\/\/dusbus.com\/hi\/","logo":{"@type":"ImageObject","inLanguage":"hi-IN","@id":"https:\/\/dusbus.com\/hi\/#\/schema\/logo\/image\/","url":"https:\/\/dusbus.com\/wp-content\/uploads\/2019\/01\/dusbus-logo.jpg","contentUrl":"https:\/\/dusbus.com\/wp-content\/uploads\/2019\/01\/dusbus-logo.jpg","width":99,"height":60,"caption":"The August Company"},"image":{"@id":"https:\/\/dusbus.com\/hi\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DusBusOfficial\/","https:\/\/x.com\/DusBusOfficial","https:\/\/www.youtube.com\/channel\/UC76y6Ny1UxTRrXGhcKW2vzA"]},{"@type":"Person","@id":"https:\/\/dusbus.com\/hi\/#\/schema\/person\/23b1b2482f8d18ed52a0e8d890d99529","name":"Pooja Jaiswal","image":{"@type":"ImageObject","inLanguage":"hi-IN","@id":"https:\/\/secure.gravatar.com\/avatar\/fde0fd69e6bde1e0b5e17aab5d3a37d04d3b6ce9b1aae1a501402489cca55abe?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fde0fd69e6bde1e0b5e17aab5d3a37d04d3b6ce9b1aae1a501402489cca55abe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fde0fd69e6bde1e0b5e17aab5d3a37d04d3b6ce9b1aae1a501402489cca55abe?s=96&d=mm&r=g","caption":"Pooja Jaiswal"},"sameAs":["http:\/\/dusbus.com\/hi"],"url":"https:\/\/dusbus.com\/hi\/author\/pooja\/"}]}},"featured_image_src":"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress.jpg","featured_image_src_square":"https:\/\/dusbus.com\/wp-content\/uploads\/2018\/03\/Dress.jpg","author_info":{"display_name":"Pooja Jaiswal","author_link":"https:\/\/dusbus.com\/hi\/author\/pooja\/"},"_links":{"self":[{"href":"https:\/\/dusbus.com\/hi\/wp-json\/wp\/v2\/posts\/43228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dusbus.com\/hi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dusbus.com\/hi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dusbus.com\/hi\/wp-json\/wp\/v2\/users\/73"}],"replies":[{"embeddable":true,"href":"https:\/\/dusbus.com\/hi\/wp-json\/wp\/v2\/comments?post=43228"}],"version-history":[{"count":0,"href":"https:\/\/dusbus.com\/hi\/wp-json\/wp\/v2\/posts\/43228\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dusbus.com\/hi\/wp-json\/wp\/v2\/media\/43249"}],"wp:attachment":[{"href":"https:\/\/dusbus.com\/hi\/wp-json\/wp\/v2\/media?parent=43228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dusbus.com\/hi\/wp-json\/wp\/v2\/categories?post=43228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dusbus.com\/hi\/wp-json\/wp\/v2\/tags?post=43228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}