{"id":131314,"date":"2020-04-18T12:15:00","date_gmt":"2020-04-18T06:45:00","guid":{"rendered":"https:\/\/dusbus.com\/?p=131314"},"modified":"2021-07-29T15:10:58","modified_gmt":"2021-07-29T09:40:58","slug":"%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c","status":"publish","type":"post","link":"https:\/\/dusbus.com\/hi\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\/","title":{"rendered":"\u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u0915\u0947 \u092c\u094d\u092f\u0942\u091f\u0940 \u0938\u093f\u0915\u094d\u0930\u0947\u091f\u094d\u0938"},"content":{"rendered":"\n<p>\u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928  \u0915\u0940 \u0938\u0941\u0902\u0926\u0930\u0924\u093e \u0915\u093e \u092a\u0930\u091a\u092e \u0915\u0947\u0935\u0932 \u092c\u0949\u0932\u0940\u0935\u0941\u0921 \u0914\u0930 \u092e\u0941\u0902\u092c\u0908 \u092e\u0947\u0902 \u0939\u0940 \u0928\u0939\u0940\u0902, \u092a\u0942\u0930\u0947 \u092d\u093e\u0930\u0924 \u092e\u0947\u0902 \u0932\u0939\u0930\u093e \u0930\u0939\u093e \u0939\u0948\u0964 \u0938\u0948\u092b \u0905\u0932\u0940 \u0916\u093e\u0928 \u0914\u0930 \u0905\u092e\u0943\u0924\u093e \u0938\u093f\u0902\u0939 \u0915\u0940 \u092c\u093f\u091f\u093f\u092f\u093e \u0930\u093e\u0928\u0940 \u0915\u0947 \u091a\u092e\u0915\u0924\u0947 \u092e\u0941\u0916\u092e\u0902\u0921\u0932 \u0914\u0930 \u0938\u094d\u0935\u0938\u094d\u0925, \u0938\u0941\u0902\u0926\u0930 \u0936\u0930\u0940\u0930 \u0928\u0947 \u092a\u0942\u0930\u0947 \u0926\u0947\u0936 \u0915\u094b \u0926\u0940\u0935\u093e\u0928\u093e \u092c\u0928\u093e \u0930\u0916\u093e \u0939\u0948\u0964 \u091a\u0932\u093f\u092f\u0947 \u0906\u091c \u091d\u093e\u0901\u0915\u0924\u0947 \u0939\u0948\u0902 \u0909\u0928\u0915\u0940 \u095b\u093f\u0902\u0926\u0917\u0940 \u092e\u0947\u0902 \u0914\u0930 \u092a\u0924\u093e \u0932\u0917\u093e\u0924\u0947 \u0939\u0948\u0902 \u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u0915\u0940 \u0938\u0941\u0902\u0926\u0930\u0924\u093e \u0915\u093e \u0930\u093e\u091c\u0964 <\/p>\n\n\n\n<p>\u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u092c\u093f\u0928\u093e \u0915\u093f\u0938\u0940 \u0938\u0902\u0926\u0947\u0939 \u0915\u0947 \u0928\u0948\u091a\u0941\u0930\u0932 \u0938\u094c\u0928\u094d\u0926\u0930\u094d\u092f \u0938\u092e\u094d\u0930\u093e\u091c\u094d\u091e\u0940 \u092e\u093e\u0928\u0940 \u091c\u093e \u0938\u0915\u0924\u0940 \u0939\u0948\u0902\u0964 \u0905\u092a\u0928\u0947 \u0907\u0938 \u092c\u0947\u0926\u093e\u0917 \u0938\u094c\u0928\u094d\u0926\u0930\u094d\u092f \u0914\u0930 \u091a\u092e\u0915\u0924\u0940 \u0924\u094d\u0935\u091a\u093e \u0915\u0940 \u0926\u0947\u0916-\u0930\u0947\u0916 \u0915\u0930\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0918\u0930\u0947\u0932\u0942 \u0909\u092a\u091a\u093e\u0930\u094b\u0902 \u0915\u093e \u0938\u0939\u093e\u0930\u093e \u0932\u0947\u0924\u0940 \u0939\u0948\u0902\u0964 \u0907\u0928 \u0909\u092a\u091a\u093e\u0930\u094b\u0902 \u092e\u0947\u0902 \u0938\u094d\u0915\u093f\u0928 \u0915\u094b \u0928\u0930\u092e \u0930\u0916\u0928\u0947, \u0930\u0902\u0917 \u0914\u0930 \u091a\u092e\u0915 \u0915\u094b \u092c\u0947\u0926\u093e\u0917 \u0930\u0916\u0947\u0902 \u0914\u0930 \u0926\u093e\u0917-\u0927\u092c\u094d\u092c\u094b\u0902 \u0938\u0947 \u092e\u0941\u0915\u094d\u0924 \u0930\u0916\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0924\u0930\u0939-\u0924\u0930\u0939 \u0915\u0947 \u0909\u092a\u093e\u092f \u0936\u093e\u092e\u093f\u0932 \u0939\u0948\u0902\u0964<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-\">\u092b\u0932\u094b\u0902 \u0915\u0947 \u0905\u0935\u0936\u0947\u0937:<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2020\/04\/fruits-for-skin-and-beauty-1024x683.jpg\" alt=\"\u0938\u0941\u0902\u0926\u0930 \u0924\u094d\u0935\u091a\u093e \u0915\u0947 \u0932\u093f\u090f \u092b\u0932\u094b\u0902 \u0915\u093e \u092a\u094d\u0930\u092f\u094b\u0917 \" class=\"wp-image-131320\" srcset=\"https:\/\/dusbus.com\/wp-content\/uploads\/2020\/04\/fruits-for-skin-and-beauty-1024x683.jpg 1024w, https:\/\/dusbus.com\/wp-content\/uploads\/2020\/04\/fruits-for-skin-and-beauty-690x460.jpg 690w, https:\/\/dusbus.com\/wp-content\/uploads\/2020\/04\/fruits-for-skin-and-beauty-150x100.jpg 150w, https:\/\/dusbus.com\/wp-content\/uploads\/2020\/04\/fruits-for-skin-and-beauty-768x512.jpg 768w, https:\/\/dusbus.com\/wp-content\/uploads\/2020\/04\/fruits-for-skin-and-beauty-600x400.jpg 600w, https:\/\/dusbus.com\/wp-content\/uploads\/2020\/04\/fruits-for-skin-and-beauty.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\u0935\u0948\u0938\u0947 \u0924\u094b \u092b\u0932\u094b\u0902 \u0915\u0947 \u0938\u0947\u0935\u0928 \u0938\u0947 \u092a\u094d\u0930\u0924\u094d\u092f\u0947\u0915 \u0935\u094d\u092f\u0915\u094d\u0924\u093f \u0938\u094d\u0935\u0938\u094d\u0925 \u0930\u0939 \u0938\u0915\u0924\u093e \u0939\u0948,\u0932\u0947\u0915\u093f\u0928 \u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u0907\u0928 \u092b\u0932\u094b\u0902 \u0915\u093e \u0938\u092e\u094d\u092a\u0942\u0930\u094d\u0923 \u0909\u092a\u092f\u094b\u0917 \u0915\u0930\u0928\u093e \u091c\u093e\u0928\u0924\u0940 \u0939\u0948\u0902\u0964 \u0909\u0928\u0915\u093e \u092e\u093e\u0928\u0928\u093e \u0939\u0948 \u0915\u093f \u092b\u0932\u094b\u0902 \u0915\u094b \u0916\u093e\u0928\u0947 \u0915\u0947 \u092c\u093e\u0926 \u0909\u0928\u0915\u0947 \u092c\u091a\u0947 \u0939\u0941\u090f \u0917\u0942\u0926\u0947 \u0914\u0930 \u091b\u093f\u0932\u0915\u094b\u0902 \u0915\u094b \u092d\u0940 \u0938\u094c\u0928\u094d\u0926\u0930\u094d\u092f \u0930\u0915\u094d\u0937\u093e \u0915\u0947 \u0909\u092a\u092f\u094b\u0917 \u092e\u0947\u0902 \u0932\u093e\u092f\u093e \u091c\u093e \u0938\u0915\u0924\u093e \u0939\u0948\u0964 <\/p>\n\n\n\n<p>\u0938\u093e\u0930\u093e \u0928\u0947 \u0905\u092a\u0928\u0947 \u0907\u0902\u091f\u0930\u0935\u094d\u092f\u0942 \u092e\u0947\u0902 \u0938\u094d\u092a\u0937\u094d\u091f \u0915\u093f\u092f\u093e \u0915\u093f \u0938\u0941\u092c\u0939 \u0915\u0947 \u0928\u093e\u0936\u094d\u0924\u0947 \u0915\u0947 \u092c\u093e\u0926 \u092b\u0932\u094b\u0902 \u0915\u093e \u091c\u094b \u092d\u0940 \u0939\u093f\u0938\u094d\u0938\u093e \u092c\u091a \u091c\u093e\u0924\u093e \u0939\u0948, \u0909\u0938\u0947 \u0935\u0939 \u0905\u092a\u0928\u0940 \u0938\u094d\u0915\u093f\u0928 \u0915\u0947 \u0932\u093f\u090f <a href=\"https:\/\/dusbus.com\/hi\/soundarya-khazana-besan-ubtan\/\">\u0909\u092c\u091f\u0928<\/a> \u092f\u093e \u092e\u093e\u0938\u094d\u0915 \u092c\u0928\u093e\u0928\u0947 \u0915\u0947 \u0915\u093e\u092e \u0932\u0947 \u0932\u0947\u0924\u0940 \u0939\u0948\u0964 \u0905\u092c \u0907\u0938\u0947 \u0915\u0939\u0924\u0947 \u0939\u0948\u0902 \u0906\u092e \u0915\u0947 \u0906\u092e \u0914\u0930 \u0917\u0941\u0920\u0932\u093f\u092f\u094b\u0902 \u0915\u0947 \u092d\u0940 \u0926\u093e\u092e\u0964<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h--1\">\u092c\u093e\u0926\u093e\u092e \u0938\u0947 \u0932\u0947\u0915\u0930 \u0936\u0939\u0926 \u0924\u0915:<\/h3>\n\n\n\n<p>\u0926\u0941\u0928\u093f\u092f\u093e \u0915\u0947 \u0915\u093f\u0938\u0940 \u092d\u0940 \u0939\u093f\u0938\u094d\u0938\u0947 \u0915\u093f \u0928\u093e\u0930\u0940 \u0939\u094b \u0909\u0938\u0947 \u0905\u092a\u0928\u0947 \u091a\u0947\u0939\u0930\u0947 \u0915\u0947 \u0938\u094c\u0928\u094d\u0926\u0930\u094d\u092f \u0938\u0947 \u0905\u0938\u0940\u092e \u092a\u094d\u092f\u093e\u0930 \u0939\u094b\u0924\u093e \u0939\u0948\u0964 \u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u092d\u0940 \u0907\u0938 \u0924\u0925\u094d\u092f \u0915\u0940 \u0905\u092a\u0935\u093e\u0926 \u0928\u0939\u0940\u0902 \u0939\u0948\u0964 \u0938\u093e\u0930\u093e \u0928\u0947 \u090f\u0915 \u092c\u093e\u0930 \u092c\u0924\u093e\u092f\u093e \u0925\u093e \u0915\u093f \u0935\u094b \u0905\u092a\u0928\u0947 \u091a\u0947\u0939\u0930\u0947 \u0915\u093e \u092e\u093e\u0938\u094d\u0915 \u092c\u0928\u093e\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0915\u0947\u0935\u0932 \u0909\u0938\u0915\u093e \u0909\u092a\u092f\u094b\u0917\u0940 \u0917\u0941\u0923 \u0926\u0947\u0916\u0924\u0940 \u0939\u0948\u0902\u0964 \u0907\u0938\u0940\u0932\u093f\u090f \u0935\u0947 \u092c\u093e\u0926\u093e\u092e \u0914\u0930 \u0936\u0939\u0926 \u0915\u093e <a href=\"https:\/\/dusbus.com\/hi\/10-homemade-besan-face-packs-for-all-skin-types\/\">\u092b\u0947\u0938 \u092a\u0948\u0915<\/a> \u0915\u093e \u092d\u0940 \u0907\u0938\u094d\u0924\u0947\u092e\u093e\u0932 \u0915\u0930\u0924\u0940 \u0939\u0948\u0902\u0964<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h--2\">\u0926\u093e\u0926\u0940 \u092e\u093e\u0901 \u0915\u0947 \u0928\u0941\u0938\u094d\u0916\u0947:<\/h3>\n\n\n\n<p>\u092f\u0939 \u092c\u093e\u0924 \u0924\u094b \u0938\u093e\u0930\u0940 \u0926\u0941\u0928\u093f\u092f\u093e \u091c\u093e\u0928\u0924\u0940 \u0939\u0948 \u0915\u093f \u0905\u092a\u0928\u0947 \u0938\u092e\u092f \u0915\u0940 \u092a\u094d\u0930\u0938\u093f\u0926\u094d\u0927 \u0905\u092d\u093f\u0928\u0947\u0924\u094d\u0930\u0940 \u0936\u0930\u094d\u092e\u0940\u0932\u093e \u091f\u0948\u0917\u094b\u0930, \u0906\u091c \u0915\u0940 \u0916\u0942\u092c\u0938\u0942\u0930\u0924 \u0905\u092d\u093f\u0928\u0947\u0924\u094d\u0930\u0940 \u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u0915\u0940 \u0926\u093e\u0926\u0940 \u0939\u0948\u0902\u0964 \u0907\u0938\u0940 \u0915\u093e\u0930\u0923 \u0938\u093e\u0930\u093e \u0909\u0928\u0915\u0947 \u0917\u0941\u0923\u094b\u0902 \u0914\u0930 \u0928\u0941\u0938\u094d\u0916\u094b\u0902 \u0915\u093e \u092a\u0942\u0930\u093e \u0909\u092a\u092f\u094b\u0917 \u0915\u0930\u0924\u0940 \u0939\u0948\u0902\u0964 <\/p>\n\n\n\n<p>\u0936\u0930\u094d\u092e\u0940\u0932\u093e \u091f\u0948\u0917\u094b\u0930 \u0928\u0947 \u0909\u0938 \u0938\u092e\u092f \u092b\u093f\u0932\u094d\u092e\u0940 \u0926\u0941\u0928\u093f\u092f\u093e \u092e\u0947\u0902 \u0915\u0926\u092e \u0930\u0916\u093e \u0925\u093e \u091c\u092c \u0938\u093f\u0928\u0947\u092e\u093e \u092c\u094d\u0932\u0947\u0915 \u090f\u0902\u0921 \u0935\u094d\u0939\u093e\u0907\u091f \u0938\u0947 \u0930\u0902\u0917\u0940\u0928 \u0926\u0941\u0928\u093f\u092f\u093e \u092e\u0947\u0902 \u092a\u094d\u0930\u0935\u0947\u0936 \u0915\u0930 \u0930\u0939\u093e \u0925\u093e\u0964 \u0907\u0938\u0932\u093f\u090f \u0936\u0930\u094d\u092e\u0940\u0932\u093e \u091f\u0948\u0917\u094b\u0930 \u0916\u0942\u092c\u0938\u0942\u0930\u0924\u0940 \u0915\u094b \u0928\u093f\u0916\u093e\u0930\u0928\u0947 \u0914\u0930 \u092c\u0928\u093e\u092f\u0947 \u0930\u0916\u0928\u0947 \u0915\u0947 \u0939\u0930 \u0938\u0902\u092d\u0935 \u0918\u0930\u0947\u0932\u0942 \u0909\u092a\u093e\u092f \u091c\u093e\u0928\u0924\u0940 \u0939\u0948\u0902\u0964 \u0907\u0938\u092e\u0947\u0902 \u0938\u092c\u0938\u0947 \u092a\u094d\u0930\u092e\u0941\u0916 \u0939\u0948 \u092d\u0930\u092a\u0942\u0930 \u0928\u0940\u0902\u0926 \u0932\u0947\u0928\u093e \u0914\u0930 \u0916\u0942\u092c&nbsp; \u0938\u093e\u0930\u093e \u092a\u093e\u0928\u0940 \u092a\u0940\u0928\u093e\u0964 \u0938\u093e\u0930\u093e \u0907\u0938\u0940 \u092c\u093e\u0924 \u0915\u094b \u0906\u0927\u093e\u0930 \u092c\u0928\u093e \u0915\u0930 \u0909\u0928\u0938\u0947 \u0916\u0942\u092c\u0938\u0942\u0930\u0924\u0940 \u0915\u0947 \u0938\u093e\u0930\u0947 \u0917\u0941\u0930 \u0938\u0940\u0916\u0924\u0940 \u0939\u0948\u0902\u0964<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h--3\">\u0915\u0947\u0936 \u0938\u094c\u0902\u0926\u0930\u094d\u092f :<\/h3>\n\n\n\n<p>\u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u0905\u092a\u0928\u0947 \u092c\u093e\u0932\u094b\u0902 \u0915\u0947 \u0938\u094c\u0902\u0926\u0930\u094d\u092f \u0915\u094b \u092c\u0928\u093e\u090f \u0930\u0916\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u092c\u0939\u0941\u0924 \u0939\u0940 \u0938\u093e\u0927\u093e\u0930\u0923 \u0918\u0930\u0947\u0932\u0942 \u0928\u0941\u0938\u094d\u0916\u0947 \u0915\u093e \u0907\u0938\u094d\u0924\u0947\u092e\u093e\u0932 \u0915\u0930\u0924\u0940 \u0939\u0948\u0902\u0964 \u0935\u094b \u0905\u092a\u0928\u0947 \u092c\u093e\u0932\u094b\u0902 \u0915\u094b \u0938\u094d\u0935\u0938\u094d\u0925 \u0914\u0930 \u0909\u0928\u0915\u0940 \u091a\u092e\u0915 \u092c\u0928\u093e\u090f \u0930\u0916\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f <a href=\"https:\/\/dusbus.com\/hi\/%e0%a4%95%e0%a5%8d%e0%a4%af%e0%a4%be-%e0%a4%aa%e0%a5%8d%e0%a4%af%e0%a4%be%e0%a5%9b-%e0%a4%95%e0%a4%be-%e0%a4%b0%e0%a4%b8-%e0%a4%9d%e0%a5%9c%e0%a4%a4%e0%a5%87-%e0%a4%ac%e0%a4%be%e0%a4%b2%e0%a5%8b\/\">\u092a\u094d\u092f\u093e\u095b \u0915\u0947 \u0930\u0938<\/a> \u0915\u093e \u0907\u0938\u094d\u0924\u0947\u092e\u093e\u0932 \u0915\u0930\u0924\u0940 \u0939\u0948\u0902\u0964 \u0907\u0938\u0938\u0947 \u0928 \u0915\u0947\u0935\u0932 \u092c\u093e\u0932\u094b\u0902 \u092e\u0947\u0902 \u092a\u094d\u0930\u0915\u0943\u0924\u093f\u0915 \u091a\u092e\u0915 \u092c\u0928\u0940 \u0930\u0939\u0924\u0940 \u0939\u0948 \u092c\u0932\u094d\u0915\u093f \u0905\u0938\u092e\u092f \u092c\u093e\u0932 \u091d\u095c\u0928\u0947 \u0938\u0947 \u092d\u0940 \u0930\u0941\u0915 \u091c\u093e\u0924\u0947 \u0939\u0948\u0902\u0964<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h--4\">\u0928\u0940\u0902\u0926 \u0914\u0930 \u092a\u093e\u0928\u0940 \u0915\u093e \u092e\u0947\u0932:<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/dusbus.com\/wp-content\/uploads\/2020\/04\/beauty-sleep-and-water-1024x683.jpg\" alt=\"\u0938\u0941\u0902\u0926\u0930 \u0924\u094d\u0935\u091a\u093e \u0915\u0947 \u0926\u094b \u0930\u093e\u091c: \u092a\u0930\u094d\u092f\u093e\u092a\u094d\u0924 \u0928\u0940\u0902\u0926 \u0914\u0930 \u0922\u0947\u0930 \u0938\u093e\u0930\u093e \u092a\u093e\u0928\u0940 \" class=\"wp-image-131323\" srcset=\"https:\/\/dusbus.com\/wp-content\/uploads\/2020\/04\/beauty-sleep-and-water-1024x683.jpg 1024w, https:\/\/dusbus.com\/wp-content\/uploads\/2020\/04\/beauty-sleep-and-water-690x460.jpg 690w, https:\/\/dusbus.com\/wp-content\/uploads\/2020\/04\/beauty-sleep-and-water-150x100.jpg 150w, https:\/\/dusbus.com\/wp-content\/uploads\/2020\/04\/beauty-sleep-and-water-768x512.jpg 768w, https:\/\/dusbus.com\/wp-content\/uploads\/2020\/04\/beauty-sleep-and-water-600x400.jpg 600w, https:\/\/dusbus.com\/wp-content\/uploads\/2020\/04\/beauty-sleep-and-water.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\u0938\u093e\u0930\u093e \u0915\u093e \u092e\u093e\u0928\u0928\u093e \u0939\u0948 \u0915\u093f \u0930\u094b\u095b \u0932\u0940 \u091c\u093e\u0928\u0947 \u0935\u093e\u0932\u0940 \u092a\u0930\u094d\u092f\u093e\u092a\u094d\u0924 \u0928\u0940\u0902\u0926 \u0914\u0930 <a href=\"https:\/\/dusbus.com\/hi\/benefits-drinking-water\/\">2-3 \u0932\u0940\u091f\u0930 \u092a\u093f\u092f\u093e \u091c\u093e\u0928\u0947 \u0935\u093e\u0932\u093e \u092a\u093e\u0928\u0940<\/a> \u0936\u093e\u0930\u0940\u0930\u093f\u0915 \u0938\u094c\u0902\u0926\u0930\u094d\u092f \u0914\u0930 \u092e\u093e\u0928\u0938\u093f\u0915 \u0936\u093e\u0902\u0924\u093f \u0915\u094b \u092c\u0928\u093e\u090f \u0930\u0916\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u095b\u0930\u0942\u0930\u0940 \u0939\u094b\u0924\u0940 \u0939\u0948\u0964 \u0907\u0938\u0932\u093f\u090f \u0935\u094b \u0905\u092a\u0928\u0947 \u092c\u093f\u095b\u0940 \u0936\u0947\u0921\u094d\u092f\u0942\u0932 \u0938\u0947 \u0938\u092e\u092f \u0928\u093f\u0915\u093e\u0932 \u0915\u0930 7-8 \u0918\u0902\u091f\u0947 \u0915\u093f \u0928\u0940\u0902\u0926 \u0932\u0947\u0928\u093e \u0928\u0939\u0940\u0902 \u092d\u0942\u0932\u0924\u0940 \u0939\u0948\u0902\u0964<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h--5\">\u0938\u094c\u0902\u0926\u0930\u094d\u092f \u0915\u0947 \u0932\u093f\u090f \u092a\u0938\u0940\u0928\u093e:<\/h3>\n\n\n\n<p>\u092b\u093f\u0932\u094d\u092e \u0938\u0941\u0902\u0926\u0930\u0940 \u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u0915\u0939\u0924\u0940 \u0939\u0948\u0902 \u0915\u093f \u0905\u0917\u0930 \u0938\u094c\u0902\u0926\u0930\u094d\u092f \u092e\u0947\u0902 \u0926\u092e\u0915 \u0915\u094b \u092c\u0928\u093e\u090f \u0930\u0916\u0928\u093e \u0939\u0948 \u0924\u092c \u0907\u0924\u0928\u093e \u0935\u0930\u094d\u0915\u093e\u0909\u091f \u0915\u0930\u0928\u093e \u091a\u093e\u0939\u093f\u090f \u0915\u093f \u0936\u0930\u0940\u0930 \u0938\u0947 \u092a\u0938\u0940\u0928\u0947 \u0915\u0947 \u0930\u0942\u092a \u092e\u0947\u0902 \u0938\u093e\u0930\u0947 \u0915\u093f\u091f\u093e\u0923\u0941 \u0914\u0930 \u0935\u093f\u0937\u093e\u0923\u0941 \u092c\u093e\u0939\u0930 \u0928\u093f\u0915\u0932 \u091c\u093e\u090f\u0901\u0964 \u0907\u0938\u0938\u0947 \u0936\u0930\u0940\u0930 \u0938\u094d\u0935\u0938\u094d\u0925 \u0935 \u0938\u0941\u0902\u0926\u0930 \u092c\u0928\u093e \u0930\u0939\u0947\u0917\u093e\u0964 \u0905\u0928\u094d\u092f \u092f\u0902\u0917 \u092c\u0949\u0932\u0940\u0935\u0941\u0921 \u0905\u092d\u093f\u0928\u0947\u0924\u094d\u0930\u093f\u092f\u094b\u0902 \u0915\u0940 \u0924\u0930\u0939 \u0938\u093e\u0930\u093e \u092d\u0940 <a href=\"https:\/\/dusbus.com\/hi\/pilates-fitness-secret-of-new-bollywood-actresses\/\">\u092a\u093f\u0932\u093e\u091f\u093f\u0938 \u0915\u0940 \u0939\u093f\u092e\u093e\u092f\u0924\u0940 <\/a>\u0939\u0948\u0902\u0964 <\/p>\n\n\n\n<p>\u0907\u0938\u0915\u0947 \u0905\u0932\u093e\u0935\u093e \u0938\u093e\u0930\u093e \u0927\u0942\u092a \u092e\u0947\u0902 \u091c\u093e\u0928\u0947 \u0938\u0947 \u092a\u0939\u0932\u0947 <a href=\"https:\/\/dusbus.com\/hi\/bharatiya-twacha-sunscreen-cream\/\">\u0938\u0928-\u0938\u094d\u0915\u094d\u0930\u0940\u0928<\/a> \u0915\u093e \u0907\u0938\u094d\u0924\u0947\u092e\u093e\u0932 \u0915\u0930\u0928\u093e \u0928\u0939\u0940\u0902 \u092d\u0942\u0932\u0924\u0940 \u0939\u0948\u0902\u0964 \u0905\u092a\u0928\u0947 \u0907\u0928 \u0909\u092a\u093e\u092f\u094b\u0902 \u0915\u0947 \u092e\u093e\u0927\u094d\u092f\u092e \u0938\u0947 \u0938\u093e\u0930\u093e \u0935\u0930\u094d\u0924\u092e\u093e\u0928 \u0938\u092e\u092f \u0915\u0940 \u0938\u0930\u094d\u0935\u0936\u094d\u0930\u0947\u0937\u094d\u0920 \u0938\u0941\u0902\u0926\u0930\u093f\u092f\u094b\u0902 \u092e\u0947\u0902 \u0917\u093f\u0928\u0940 \u091c\u093e \u0938\u0915\u0924\u0940 \u0939\u0948\u0902\u0964<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u0915\u0940 \u0938\u0941\u0902\u0926\u0930\u0924\u093e \u0915\u093e \u092a\u0930\u091a\u092e \u0915\u0947\u0935\u0932 \u092c\u0949\u0932\u0940\u0935\u0941\u0921 \u0914\u0930 \u092e\u0941\u0902\u092c\u0908 \u092e\u0947\u0902 \u0939\u0940 \u0928\u0939\u0940\u0902, \u092a\u0942\u0930\u0947 \u092d\u093e\u0930\u0924 \u092e\u0947\u0902 \u0932\u0939\u0930\u093e \u0930\u0939\u093e \u0939\u0948\u0964 \u0938\u0948\u092b \u0905\u0932\u0940 \u0916\u093e\u0928 \u0914\u0930 \u0905\u092e\u0943\u0924\u093e \u0938\u093f\u0902\u0939 \u0915\u0940 \u092c\u093f\u091f\u093f\u092f\u093e \u0930\u093e\u0928\u0940 \u0915\u0947 \u091a\u092e\u0915\u0924\u0947 \u092e\u0941\u0916\u092e\u0902\u0921\u0932 \u0914\u0930 \u0938\u094d\u0935\u0938\u094d\u0925, \u0938\u0941\u0902\u0926\u0930 \u0936\u0930\u0940\u0930 \u0928\u0947 \u092a\u0942\u0930\u0947 \u0926\u0947\u0936 \u0915\u094b \u0926\u0940\u0935\u093e\u0928\u093e \u092c\u0928\u093e \u0930\u0916\u093e \u0939\u0948\u0964 \u091a\u0932\u093f\u092f\u0947 \u0906\u091c \u091d\u093e\u0901\u0915\u0924\u0947 \u0939\u0948\u0902 \u0909\u0928\u0915\u0940 \u095b\u093f\u0902\u0926\u0917\u0940 \u092e\u0947\u0902 \u0914\u0930 \u092a\u0924\u093e \u0932\u0917\u093e\u0924\u0947 \u0939\u0948\u0902 [&hellip;]<\/p>\n","protected":false},"author":50,"featured_media":131317,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[89,223],"tags":[],"class_list":{"0":"post-131314","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-personal-care-hi","8":"category-skin-care-hindi","9":"entry"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u0915\u0947 \u092c\u094d\u092f\u0942\u091f\u0940 \u0938\u093f\u0915\u094d\u0930\u0947\u091f\u094d\u0938 - DusBus<\/title>\n<meta name=\"description\" content=\"\u0938\u0948\u092b \u0914\u0930 \u0905\u092e\u0943\u0924\u093e \u0938\u093f\u0902\u0939 \u0915\u0940 \u092c\u093f\u091f\u093f\u092f\u093e \u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u0928\u0947 \u0905\u092a\u0928\u0940 \u0938\u0941\u0902\u0926\u0930\u0924\u093e \u0938\u0947 \u092a\u0942\u0930\u0947 \u092d\u093e\u0930\u0924 \u0915\u094b \u0926\u0940\u0935\u093e\u0928\u093e \u092c\u0928\u093e \u0930\u0916\u093e \u0939\u0948\u0964 \u091a\u0932\u093f\u092f\u0947 \u091c\u093e\u0928\u0924\u0947 \u0939\u0948\u0902 \u0938\u093e\u0930\u093e \u0915\u0940 \u0938\u0941\u0902\u0926\u0930 \u0924\u094d\u0935\u091a\u093e \u0915\u0947 \u092a\u0940\u091b\u0947 \u091b\u093f\u092a\u0947 \u0915\u093e\u0930\u0923\u094b\u0902 \u0915\u094b\u0964\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dusbus.com\/hi\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\/\" \/>\n<meta property=\"og:locale\" content=\"hi_IN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u0915\u0947 \u092c\u094d\u092f\u0942\u091f\u0940 \u0938\u093f\u0915\u094d\u0930\u0947\u091f\u094d\u0938 - DusBus\" \/>\n<meta property=\"og:description\" content=\"\u0938\u0948\u092b \u0914\u0930 \u0905\u092e\u0943\u0924\u093e \u0938\u093f\u0902\u0939 \u0915\u0940 \u092c\u093f\u091f\u093f\u092f\u093e \u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u0928\u0947 \u0905\u092a\u0928\u0940 \u0938\u0941\u0902\u0926\u0930\u0924\u093e \u0938\u0947 \u092a\u0942\u0930\u0947 \u092d\u093e\u0930\u0924 \u0915\u094b \u0926\u0940\u0935\u093e\u0928\u093e \u092c\u0928\u093e \u0930\u0916\u093e \u0939\u0948\u0964 \u091a\u0932\u093f\u092f\u0947 \u091c\u093e\u0928\u0924\u0947 \u0939\u0948\u0902 \u0938\u093e\u0930\u093e \u0915\u0940 \u0938\u0941\u0902\u0926\u0930 \u0924\u094d\u0935\u091a\u093e \u0915\u0947 \u092a\u0940\u091b\u0947 \u091b\u093f\u092a\u0947 \u0915\u093e\u0930\u0923\u094b\u0902 \u0915\u094b\u0964\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dusbus.com\/hi\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\/\" \/>\n<meta property=\"og:site_name\" content=\"DusBus\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DusBusOfficial\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-18T06:45:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-29T09:40:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dusbus.com\/wp-content\/uploads\/2020\/04\/beauty-secrets-of-sara-ali-khan.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Charu Dev\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DusBusOfficial\" \/>\n<meta name=\"twitter:site\" content=\"@DusBusOfficial\" \/>\n<meta name=\"twitter:label1\" content=\"\u0926\u094d\u0935\u093e\u0930\u093e \u0932\u093f\u0916\u093f\u0924\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u091a\u093e\u0930\u0941 \u0926\u0947\u0935\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0905\u0928\u0941\u092e\u093e\u0928\u093f\u0924 \u092a\u0922\u093c\u0928\u0947 \u0915\u093e \u0938\u092e\u092f\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 \u092e\u093f\u0928\u091f\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\\\/\"},\"author\":{\"name\":\"Charu Dev\",\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/#\\\/schema\\\/person\\\/1a3548d0541327253b116c57d8c8ac6d\"},\"headline\":\"\u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u0915\u0947 \u092c\u094d\u092f\u0942\u091f\u0940 \u0938\u093f\u0915\u094d\u0930\u0947\u091f\u094d\u0938\",\"datePublished\":\"2020-04-18T06:45:00+00:00\",\"dateModified\":\"2021-07-29T09:40:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\\\/\"},\"wordCount\":7,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dusbus.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/sara-ali-khan-beauty-secret.jpg\",\"articleSection\":[\"Personal Care\",\"\u0938\u094d\u0915\u093f\u0928 \u0915\u0947\u092f\u0930\"],\"inLanguage\":\"hi-IN\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dusbus.com\\\/hi\\\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\\\/\",\"url\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\\\/\",\"name\":\"\u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u0915\u0947 \u092c\u094d\u092f\u0942\u091f\u0940 \u0938\u093f\u0915\u094d\u0930\u0947\u091f\u094d\u0938 - DusBus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dusbus.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/sara-ali-khan-beauty-secret.jpg\",\"datePublished\":\"2020-04-18T06:45:00+00:00\",\"dateModified\":\"2021-07-29T09:40:58+00:00\",\"description\":\"\u0938\u0948\u092b \u0914\u0930 \u0905\u092e\u0943\u0924\u093e \u0938\u093f\u0902\u0939 \u0915\u0940 \u092c\u093f\u091f\u093f\u092f\u093e \u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u0928\u0947 \u0905\u092a\u0928\u0940 \u0938\u0941\u0902\u0926\u0930\u0924\u093e \u0938\u0947 \u092a\u0942\u0930\u0947 \u092d\u093e\u0930\u0924 \u0915\u094b \u0926\u0940\u0935\u093e\u0928\u093e \u092c\u0928\u093e \u0930\u0916\u093e \u0939\u0948\u0964 \u091a\u0932\u093f\u092f\u0947 \u091c\u093e\u0928\u0924\u0947 \u0939\u0948\u0902 \u0938\u093e\u0930\u093e \u0915\u0940 \u0938\u0941\u0902\u0926\u0930 \u0924\u094d\u0935\u091a\u093e \u0915\u0947 \u092a\u0940\u091b\u0947 \u091b\u093f\u092a\u0947 \u0915\u093e\u0930\u0923\u094b\u0902 \u0915\u094b\u0964\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\\\/#breadcrumb\"},\"inLanguage\":\"hi-IN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dusbus.com\\\/hi\\\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hi-IN\",\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dusbus.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/sara-ali-khan-beauty-secret.jpg\",\"contentUrl\":\"https:\\\/\\\/dusbus.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/sara-ali-khan-beauty-secret.jpg\",\"width\":1200,\"height\":675,\"caption\":\"\u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u0915\u0940 \u0938\u0941\u0902\u0926\u0930\u0924\u093e \u0915\u093e \u0930\u093e\u091c\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u0915\u0947 \u092c\u094d\u092f\u0942\u091f\u0940 \u0938\u093f\u0915\u094d\u0930\u0947\u091f\u094d\u0938\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/#website\",\"url\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/\",\"name\":\"DusBus\",\"description\":\"Driving E-Commerce\",\"publisher\":{\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hi-IN\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/#organization\",\"name\":\"The August Company\",\"url\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hi-IN\",\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dusbus.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/dusbus-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/dusbus.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/dusbus-logo.jpg\",\"width\":99,\"height\":60,\"caption\":\"The August Company\"},\"image\":{\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DusBusOfficial\\\/\",\"https:\\\/\\\/x.com\\\/DusBusOfficial\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC76y6Ny1UxTRrXGhcKW2vzA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/#\\\/schema\\\/person\\\/1a3548d0541327253b116c57d8c8ac6d\",\"name\":\"Charu Dev\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hi-IN\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99cb125d1202ed6704303910619cb5d345ee1b472d273fa3810aed6ee156c32b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99cb125d1202ed6704303910619cb5d345ee1b472d273fa3810aed6ee156c32b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99cb125d1202ed6704303910619cb5d345ee1b472d273fa3810aed6ee156c32b?s=96&d=mm&r=g\",\"caption\":\"Charu Dev\"},\"url\":\"https:\\\/\\\/dusbus.com\\\/hi\\\/author\\\/charu\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u0915\u0947 \u092c\u094d\u092f\u0942\u091f\u0940 \u0938\u093f\u0915\u094d\u0930\u0947\u091f\u094d\u0938 - DusBus","description":"\u0938\u0948\u092b \u0914\u0930 \u0905\u092e\u0943\u0924\u093e \u0938\u093f\u0902\u0939 \u0915\u0940 \u092c\u093f\u091f\u093f\u092f\u093e \u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u0928\u0947 \u0905\u092a\u0928\u0940 \u0938\u0941\u0902\u0926\u0930\u0924\u093e \u0938\u0947 \u092a\u0942\u0930\u0947 \u092d\u093e\u0930\u0924 \u0915\u094b \u0926\u0940\u0935\u093e\u0928\u093e \u092c\u0928\u093e \u0930\u0916\u093e \u0939\u0948\u0964 \u091a\u0932\u093f\u092f\u0947 \u091c\u093e\u0928\u0924\u0947 \u0939\u0948\u0902 \u0938\u093e\u0930\u093e \u0915\u0940 \u0938\u0941\u0902\u0926\u0930 \u0924\u094d\u0935\u091a\u093e \u0915\u0947 \u092a\u0940\u091b\u0947 \u091b\u093f\u092a\u0947 \u0915\u093e\u0930\u0923\u094b\u0902 \u0915\u094b\u0964","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dusbus.com\/hi\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\/","og_locale":"hi_IN","og_type":"article","og_title":"\u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u0915\u0947 \u092c\u094d\u092f\u0942\u091f\u0940 \u0938\u093f\u0915\u094d\u0930\u0947\u091f\u094d\u0938 - DusBus","og_description":"\u0938\u0948\u092b \u0914\u0930 \u0905\u092e\u0943\u0924\u093e \u0938\u093f\u0902\u0939 \u0915\u0940 \u092c\u093f\u091f\u093f\u092f\u093e \u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u0928\u0947 \u0905\u092a\u0928\u0940 \u0938\u0941\u0902\u0926\u0930\u0924\u093e \u0938\u0947 \u092a\u0942\u0930\u0947 \u092d\u093e\u0930\u0924 \u0915\u094b \u0926\u0940\u0935\u093e\u0928\u093e \u092c\u0928\u093e \u0930\u0916\u093e \u0939\u0948\u0964 \u091a\u0932\u093f\u092f\u0947 \u091c\u093e\u0928\u0924\u0947 \u0939\u0948\u0902 \u0938\u093e\u0930\u093e \u0915\u0940 \u0938\u0941\u0902\u0926\u0930 \u0924\u094d\u0935\u091a\u093e \u0915\u0947 \u092a\u0940\u091b\u0947 \u091b\u093f\u092a\u0947 \u0915\u093e\u0930\u0923\u094b\u0902 \u0915\u094b\u0964","og_url":"https:\/\/dusbus.com\/hi\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\/","og_site_name":"DusBus","article_publisher":"https:\/\/www.facebook.com\/DusBusOfficial\/","article_published_time":"2020-04-18T06:45:00+00:00","article_modified_time":"2021-07-29T09:40:58+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/dusbus.com\/wp-content\/uploads\/2020\/04\/beauty-secrets-of-sara-ali-khan.jpg","type":"image\/jpeg"}],"author":"Charu Dev","twitter_card":"summary_large_image","twitter_creator":"@DusBusOfficial","twitter_site":"@DusBusOfficial","twitter_misc":{"\u0926\u094d\u0935\u093e\u0930\u093e \u0932\u093f\u0916\u093f\u0924":"\u091a\u093e\u0930\u0941 \u0926\u0947\u0935","\u0905\u0928\u0941\u092e\u093e\u0928\u093f\u0924 \u092a\u0922\u093c\u0928\u0947 \u0915\u093e \u0938\u092e\u092f":"4 \u092e\u093f\u0928\u091f"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dusbus.com\/hi\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\/#article","isPartOf":{"@id":"https:\/\/dusbus.com\/hi\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\/"},"author":{"name":"Charu Dev","@id":"https:\/\/dusbus.com\/hi\/#\/schema\/person\/1a3548d0541327253b116c57d8c8ac6d"},"headline":"\u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u0915\u0947 \u092c\u094d\u092f\u0942\u091f\u0940 \u0938\u093f\u0915\u094d\u0930\u0947\u091f\u094d\u0938","datePublished":"2020-04-18T06:45:00+00:00","dateModified":"2021-07-29T09:40:58+00:00","mainEntityOfPage":{"@id":"https:\/\/dusbus.com\/hi\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\/"},"wordCount":7,"commentCount":0,"publisher":{"@id":"https:\/\/dusbus.com\/hi\/#organization"},"image":{"@id":"https:\/\/dusbus.com\/hi\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\/#primaryimage"},"thumbnailUrl":"https:\/\/dusbus.com\/wp-content\/uploads\/2020\/04\/sara-ali-khan-beauty-secret.jpg","articleSection":["Personal Care","\u0938\u094d\u0915\u093f\u0928 \u0915\u0947\u092f\u0930"],"inLanguage":"hi-IN","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dusbus.com\/hi\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dusbus.com\/hi\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\/","url":"https:\/\/dusbus.com\/hi\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\/","name":"\u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u0915\u0947 \u092c\u094d\u092f\u0942\u091f\u0940 \u0938\u093f\u0915\u094d\u0930\u0947\u091f\u094d\u0938 - DusBus","isPartOf":{"@id":"https:\/\/dusbus.com\/hi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dusbus.com\/hi\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\/#primaryimage"},"image":{"@id":"https:\/\/dusbus.com\/hi\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\/#primaryimage"},"thumbnailUrl":"https:\/\/dusbus.com\/wp-content\/uploads\/2020\/04\/sara-ali-khan-beauty-secret.jpg","datePublished":"2020-04-18T06:45:00+00:00","dateModified":"2021-07-29T09:40:58+00:00","description":"\u0938\u0948\u092b \u0914\u0930 \u0905\u092e\u0943\u0924\u093e \u0938\u093f\u0902\u0939 \u0915\u0940 \u092c\u093f\u091f\u093f\u092f\u093e \u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u0928\u0947 \u0905\u092a\u0928\u0940 \u0938\u0941\u0902\u0926\u0930\u0924\u093e \u0938\u0947 \u092a\u0942\u0930\u0947 \u092d\u093e\u0930\u0924 \u0915\u094b \u0926\u0940\u0935\u093e\u0928\u093e \u092c\u0928\u093e \u0930\u0916\u093e \u0939\u0948\u0964 \u091a\u0932\u093f\u092f\u0947 \u091c\u093e\u0928\u0924\u0947 \u0939\u0948\u0902 \u0938\u093e\u0930\u093e \u0915\u0940 \u0938\u0941\u0902\u0926\u0930 \u0924\u094d\u0935\u091a\u093e \u0915\u0947 \u092a\u0940\u091b\u0947 \u091b\u093f\u092a\u0947 \u0915\u093e\u0930\u0923\u094b\u0902 \u0915\u094b\u0964","breadcrumb":{"@id":"https:\/\/dusbus.com\/hi\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\/#breadcrumb"},"inLanguage":"hi-IN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dusbus.com\/hi\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\/"]}]},{"@type":"ImageObject","inLanguage":"hi-IN","@id":"https:\/\/dusbus.com\/hi\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\/#primaryimage","url":"https:\/\/dusbus.com\/wp-content\/uploads\/2020\/04\/sara-ali-khan-beauty-secret.jpg","contentUrl":"https:\/\/dusbus.com\/wp-content\/uploads\/2020\/04\/sara-ali-khan-beauty-secret.jpg","width":1200,"height":675,"caption":"\u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u0915\u0940 \u0938\u0941\u0902\u0926\u0930\u0924\u093e \u0915\u093e \u0930\u093e\u091c"},{"@type":"BreadcrumbList","@id":"https:\/\/dusbus.com\/hi\/%e0%a4%b8%e0%a4%be%e0%a4%b0%e0%a4%be-%e0%a4%85%e0%a4%b2%e0%a5%80-%e0%a4%96%e0%a4%be%e0%a4%a8-%e0%a4%b8%e0%a5%81%e0%a4%82%e0%a4%a6%e0%a4%b0%e0%a4%a4%e0%a4%be-%e0%a4%b0%e0%a4%be%e0%a4%9c\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dusbus.com\/hi\/"},{"@type":"ListItem","position":2,"name":"\u0938\u093e\u0930\u093e \u0905\u0932\u0940 \u0916\u093e\u0928 \u0915\u0947 \u092c\u094d\u092f\u0942\u091f\u0940 \u0938\u093f\u0915\u094d\u0930\u0947\u091f\u094d\u0938"}]},{"@type":"WebSite","@id":"https:\/\/dusbus.com\/hi\/#website","url":"https:\/\/dusbus.com\/hi\/","name":"DusBus","description":"Driving E-Commerce","publisher":{"@id":"https:\/\/dusbus.com\/hi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dusbus.com\/hi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hi-IN"},{"@type":"Organization","@id":"https:\/\/dusbus.com\/hi\/#organization","name":"The August Company","url":"https:\/\/dusbus.com\/hi\/","logo":{"@type":"ImageObject","inLanguage":"hi-IN","@id":"https:\/\/dusbus.com\/hi\/#\/schema\/logo\/image\/","url":"https:\/\/dusbus.com\/wp-content\/uploads\/2019\/01\/dusbus-logo.jpg","contentUrl":"https:\/\/dusbus.com\/wp-content\/uploads\/2019\/01\/dusbus-logo.jpg","width":99,"height":60,"caption":"The August Company"},"image":{"@id":"https:\/\/dusbus.com\/hi\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DusBusOfficial\/","https:\/\/x.com\/DusBusOfficial","https:\/\/www.youtube.com\/channel\/UC76y6Ny1UxTRrXGhcKW2vzA"]},{"@type":"Person","@id":"https:\/\/dusbus.com\/hi\/#\/schema\/person\/1a3548d0541327253b116c57d8c8ac6d","name":"Charu Dev","image":{"@type":"ImageObject","inLanguage":"hi-IN","@id":"https:\/\/secure.gravatar.com\/avatar\/99cb125d1202ed6704303910619cb5d345ee1b472d273fa3810aed6ee156c32b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/99cb125d1202ed6704303910619cb5d345ee1b472d273fa3810aed6ee156c32b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/99cb125d1202ed6704303910619cb5d345ee1b472d273fa3810aed6ee156c32b?s=96&d=mm&r=g","caption":"Charu Dev"},"url":"https:\/\/dusbus.com\/hi\/author\/charu\/"}]}},"featured_image_src":"https:\/\/dusbus.com\/wp-content\/uploads\/2020\/04\/sara-ali-khan-beauty-secret.jpg","featured_image_src_square":"https:\/\/dusbus.com\/wp-content\/uploads\/2020\/04\/sara-ali-khan-beauty-secret.jpg","author_info":{"display_name":"\u091a\u093e\u0930\u0941 \u0926\u0947\u0935","author_link":"https:\/\/dusbus.com\/hi\/author\/charu\/"},"_links":{"self":[{"href":"https:\/\/dusbus.com\/hi\/wp-json\/wp\/v2\/posts\/131314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dusbus.com\/hi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dusbus.com\/hi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dusbus.com\/hi\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/dusbus.com\/hi\/wp-json\/wp\/v2\/comments?post=131314"}],"version-history":[{"count":7,"href":"https:\/\/dusbus.com\/hi\/wp-json\/wp\/v2\/posts\/131314\/revisions"}],"predecessor-version":[{"id":194451,"href":"https:\/\/dusbus.com\/hi\/wp-json\/wp\/v2\/posts\/131314\/revisions\/194451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dusbus.com\/hi\/wp-json\/wp\/v2\/media\/131317"}],"wp:attachment":[{"href":"https:\/\/dusbus.com\/hi\/wp-json\/wp\/v2\/media?parent=131314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dusbus.com\/hi\/wp-json\/wp\/v2\/categories?post=131314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dusbus.com\/hi\/wp-json\/wp\/v2\/tags?post=131314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}